{"id":511,"date":"2025-12-19T04:46:42","date_gmt":"2025-12-19T04:46:42","guid":{"rendered":"https:\/\/lviu.university\/?page_id=511"},"modified":"2026-04-21T07:45:52","modified_gmt":"2026-04-21T07:45:52","slug":"accreditations-and-recognitions","status":"publish","type":"page","link":"https:\/\/lviu.university\/en_us\/accreditations-and-recognitions\/","title":{"rendered":"Accreditations and Recognitions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"511\" class=\"elementor elementor-511\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73cfe9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73cfe9b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-add73f6\" data-id=\"add73f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-419444f elementor-widget elementor-widget-heading\" data-id=\"419444f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Accreditations and Recognitions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22ff842 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22ff842\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bfd6a5d\" data-id=\"bfd6a5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c83b79 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"7c83b79\" data-element_type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion floating-style\" id=\"accordion-6a97d361721a3\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-7c83b79\">\n                        <a href=\"#collapse-2c9e4cb6a97d361721a3\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-2c9e4cb6a97d361721a3\" aria-expanded=\"true\" aria-controls=\"Collapse-2c9e4cb6a97d361721a3\">\n                            \n                            <span class=\"ekit-accordion-title\">Florida Department of State<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-2c9e4cb6a97d361721a3\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-7c83b79\" data-parent=\"#accordion-6a97d361721a3\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><img decoding=\"async\" class=\"alignnone wp-image-514\" src=\"https:\/\/lviu.university\/wp-content\/uploads\/2025\/12\/seal_of_florida-300x300-1.png\" alt=\"\" width=\"151\" height=\"151\" srcset=\"https:\/\/lviu.university\/wp-content\/uploads\/2025\/12\/seal_of_florida-300x300-1.png 300w, https:\/\/lviu.university\/wp-content\/uploads\/2025\/12\/seal_of_florida-300x300-1-150x150.png 150w\" sizes=\"(max-width: 151px) 100vw, 151px\" \/><\/p><p><strong>AUTHORIZATION: <span style=\"color: #0000ff\">P25000067293<\/span><\/strong><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-7c83b79\">\n                        <a href=\"#collapse-0f201ab6a97d361721a3\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0f201ab6a97d361721a3\" aria-expanded=\"false\" aria-controls=\"Collapse-0f201ab6a97d361721a3\">\n                            \n                            <span class=\"ekit-accordion-title\">American Council for Academic Accreditation<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0f201ab6a97d361721a3\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-7c83b79\" data-parent=\"#accordion-6a97d361721a3\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <figure id=\"attachment_515\" aria-describedby=\"caption-attachment-515\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-515 size-medium\" src=\"https:\/\/lviu.university\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dic-2025-12_28_48-a.m-e1766118853119-300x123.png\" alt=\"\" width=\"300\" height=\"123\" srcset=\"https:\/\/lviu.university\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dic-2025-12_28_48-a.m-e1766118853119-300x123.png 300w, https:\/\/lviu.university\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dic-2025-12_28_48-a.m-e1766118853119-1024x418.png 1024w, https:\/\/lviu.university\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dic-2025-12_28_48-a.m-e1766118853119-768x314.png 768w, https:\/\/lviu.university\/wp-content\/uploads\/2025\/12\/ChatGPT-Image-19-dic-2025-12_28_48-a.m-e1766118853119.png 1060w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-515\" class=\"wp-caption-text\"><strong>ACCREDITATION RESOLUTION No. <span style=\"color: #0000ff\">202512001-ACAA<\/span><\/strong><\/figcaption><\/figure>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-7c83b79\">\n                        <a href=\"#collapse-d3f325e6a97d361721a3\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-d3f325e6a97d361721a3\" aria-expanded=\"false\" aria-controls=\"Collapse-d3f325e6a97d361721a3\">\n                            \n                            <span class=\"ekit-accordion-title\">American Association for Higher Education<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-d3f325e6a97d361721a3\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-7c83b79\" data-parent=\"#accordion-6a97d361721a3\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.aahea.org\/images\/aahea-logo.png\" alt=\"American Association for Higher Education - American Association of Higher  Education (AAHE)\" \/><strong>ACCREDITATION RESOLUTION No. <span style=\"color: #0000ff\">202512001-ACAA<\/span><\/strong><\/p><p>\u00a0<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-876\" src=\"https:\/\/lviu.university\/wp-content\/uploads\/2026\/04\/IMG_6448-300x235.jpg\" alt=\"\" width=\"300\" height=\"235\" srcset=\"https:\/\/lviu.university\/wp-content\/uploads\/2026\/04\/IMG_6448-300x235.jpg 300w, https:\/\/lviu.university\/wp-content\/uploads\/2026\/04\/IMG_6448-1024x802.jpg 1024w, https:\/\/lviu.university\/wp-content\/uploads\/2026\/04\/IMG_6448-768x602.jpg 768w, https:\/\/lviu.university\/wp-content\/uploads\/2026\/04\/IMG_6448-1536x1204.jpg 1536w, https:\/\/lviu.university\/wp-content\/uploads\/2026\/04\/IMG_6448-15x12.jpg 15w, https:\/\/lviu.university\/wp-content\/uploads\/2026\/04\/IMG_6448.jpg 1594w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-7c83b79\">\n                        <a href=\"#collapse-9b652d96a97d361721a3\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9b652d96a97d361721a3\" aria-expanded=\"false\" aria-controls=\"Collapse-9b652d96a97d361721a3\">\n                            \n                            <span class=\"ekit-accordion-title\">United States Distance Learning Association<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9b652d96a97d361721a3\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-7c83b79\" data-parent=\"#accordion-6a97d361721a3\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>ACCREDITATION IN PROCESS<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7202737 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7202737\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9242c52\" data-id=\"9242c52\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8e6069 elementor-widget elementor-widget-spacer\" data-id=\"f8e6069\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Accreditations and Recognitions Florida Department of State AUTHORIZATION: P25000067293 American Council for Academic Accreditation ACCREDITATION RESOLUTION No. 202512001-ACAA American Association [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-511","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lviu.university\/en_us\/wp-json\/wp\/v2\/pages\/511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lviu.university\/en_us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lviu.university\/en_us\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lviu.university\/en_us\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lviu.university\/en_us\/wp-json\/wp\/v2\/comments?post=511"}],"version-history":[{"count":28,"href":"https:\/\/lviu.university\/en_us\/wp-json\/wp\/v2\/pages\/511\/revisions"}],"predecessor-version":[{"id":879,"href":"https:\/\/lviu.university\/en_us\/wp-json\/wp\/v2\/pages\/511\/revisions\/879"}],"wp:attachment":[{"href":"https:\/\/lviu.university\/en_us\/wp-json\/wp\/v2\/media?parent=511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}